{"id":94259,"date":"2026-08-27T16:36:29","date_gmt":"2026-08-27T14:36:29","guid":{"rendered":"https:\/\/amanos.shop\/?post_type=product&#038;p=94259"},"modified":"2026-08-27T16:36:29","modified_gmt":"2026-08-27T14:36:29","slug":"weise-kapa-plast-leichtschaumplatte-tannenbaumform-einseitiger-druck","status":"publish","type":"product","link":"https:\/\/amanos.shop\/de\/produkt\/weise-kapa-plast-leichtschaumplatte-tannenbaumform-einseitiger-druck\/","title":{"rendered":"Wei\u00dfe KAPA\u00ae plast Leichtschaumplatte \u2013 Tannenbaumform \u2013 einseitiger Druck"},"content":{"rendered":"<h2>Wei\u00dfe KAPA\u00ae plast Leichtschaumplatte \u2013 Tannenbaumform \u2013 einseitiger Druck<\/h2>\n<p>Die wei\u00dfe KAPA\u00ae plast Leichtschaumplatte eignet sich f\u00fcr individuell gestaltete Schilder und Werbetafeln. Sie ist mit <strong>UV-DTF<\/strong> individualisierbar und wird einseitig bedruckt.<\/p>\n<h3>Gr\u00f6\u00dfe<\/h3>\n<p>Verf\u00fcgbare Gr\u00f6\u00dfen bei Amanos: 10 \u00d7 10 cm, 20 \u00d7 20 cm, 35 \u00d7 35 cm.<\/p>\n<h3>Materialien und Optionen<\/h3>\n<ul>\n<li>Wei\u00dfe KAPA\u00ae plast Leichtschaumplatte, 10 mm stark<\/li>\n<\/ul>\n<h3>Designmodus<\/h3>\n<p>W\u00e4hlen Sie entweder dasselbe Design f\u00fcr alle Exemplare oder ein individuelles Design pro Exemplar.<\/p>\n<h3>Druckseite<\/h3>\n<p>Der Druck erfolgt <strong>einseitig<\/strong>.<\/p>\n<h3>Druckdatei<\/h3>\n<p>Laden Sie Ihre druckfertige Datei hoch oder nutzen Sie den bei Amanos verf\u00fcgbaren Designservice, um Ihre Bestellung abzuschlie\u00dfen.<\/p>\n<p><strong>Preis:<\/strong> Der angezeigte St\u00fcckpreis enth\u00e4lt 19 % MwSt. und richtet sich nach Gr\u00f6\u00dfe, Material und Designmodus, sofern diese Optionen verf\u00fcgbar sind.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Wei\u00dfe KAPA\u00ae plast Leichtschaumplatte \u2013 Tannenbaumform \u2013 einseitiger Druck. Individuell mit UV-DTF bedruckbar. Verf\u00fcgbare Gr\u00f6\u00dfen bei Amanos: 10 \u00d7 10 cm, 20 \u00d7 20 cm, 35 \u00d7 35 cm. W\u00e4hlen Sie Gr\u00f6\u00dfe, Material und Designmodus und laden Sie anschlie\u00dfend Ihre Druckdatei hoch. Der angezeigte St\u00fcckpreis enth\u00e4lt 19 % MwSt. und richtet sich nach den gew\u00e4hlten Optionen.<\/p>\n","protected":false},"featured_media":0,"comment_status":"open","ping_status":"closed","template":"","meta":{"nf_dc_page":""},"product_brand":[],"product_cat":[3845],"product_tag":[3657,3866,3867,3500,3732,3846],"class_list":["post-94259","product","type-product","status-publish","product_cat-schilder-und-werbeschilder","product_tag-individueller-druck","product_tag-kapa","product_tag-leichtschaum","product_tag-uv-dtf","product_tag-werbeschilder","product_tag-werbeschilder-2","first","instock","taxable","shipping-taxable","purchasable","product-type-variable","has-default-attributes","add-to-wishlist-before_image"],"_links":{"self":[{"href":"https:\/\/amanos.shop\/de\/wp-json\/wp\/v2\/product\/94259","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/amanos.shop\/de\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/amanos.shop\/de\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/amanos.shop\/de\/wp-json\/wp\/v2\/comments?post=94259"}],"wp:attachment":[{"href":"https:\/\/amanos.shop\/de\/wp-json\/wp\/v2\/media?parent=94259"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/amanos.shop\/de\/wp-json\/wp\/v2\/product_brand?post=94259"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/amanos.shop\/de\/wp-json\/wp\/v2\/product_cat?post=94259"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/amanos.shop\/de\/wp-json\/wp\/v2\/product_tag?post=94259"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}