{"id":61832,"date":"2026-08-24T16:57:38","date_gmt":"2026-08-24T14:57:38","guid":{"rendered":"https:\/\/amanos.shop\/?post_type=product&#038;p=61832"},"modified":"2026-08-24T16:57:39","modified_gmt":"2026-08-24T14:57:39","slug":"aluminiumverbundplatte-gold-geburstet-freiform-mit-bis-zu-4-konturschnitten-einseitig-bedruckt","status":"publish","type":"product","link":"https:\/\/amanos.shop\/de\/produkt\/aluminiumverbundplatte-gold-geburstet-freiform-mit-bis-zu-4-konturschnitten-einseitig-bedruckt\/","title":{"rendered":"Aluminiumverbundplatte Gold geb\u00fcrstet \u2013 Freiform mit bis zu 4 Konturschnitten \u2013 einseitig bedruckt"},"content":{"rendered":"<h2>Aluminiumverbundplatte Gold geb\u00fcrstet \u2013 Freiform mit bis zu 4 Konturschnitten \u2013 einseitig bedruckt<\/h2>\n<p>Aluminiumverbundplatte Gold geb\u00fcrstet als Freiform mit bis zu 4 Konturschnitten mit einseitigem Druck. Ideal f\u00fcr individuell gestaltete Schilder und Werbeschilder und entsprechend den verf\u00fcgbaren Produktoptionen konfigurierbar.<\/p>\n<h3>Verf\u00fcgbare Gr\u00f6\u00dfen<\/h3>\n<ul>\n<li>10 \u00d7 10 cm<\/li>\n<li>20 \u00d7 20 cm<\/li>\n<li>35 \u00d7 35 cm<\/li>\n<\/ul>\n<h3>Materialien und Veredelungen<\/h3>\n<ul>\n<li>Aluminiumverbundplatte Gold geb\u00fcrstet, 3 mm stark<\/li>\n<li>Aluminiumverbundplatte Gold geb\u00fcrstet, 3 mm stark \u2013 partielle Wei\u00dfunterlegung<\/li>\n<li>Aluminiumverbundplatte Gold geb\u00fcrstet, 3 mm stark \u2013 partieller UV-Glanzlack<\/li>\n<li>Aluminiumverbundplatte Gold geb\u00fcrstet, 3 mm stark \u2013 vollfl\u00e4chiger UV-Glanzlack<\/li>\n<li>Aluminiumverbundplatte Gold geb\u00fcrstet, 3 mm stark \u2013 partielle Wei\u00dfunterlegung + vollfl\u00e4chiger UV-Glanzlack<\/li>\n<li>Aluminiumverbundplatte Gold geb\u00fcrstet, 3 mm stark \u2013 partielle Wei\u00dfunterlegung + partieller UV-Glanzlack<\/li>\n<\/ul>\n<h3>Personalisierungsoptionen<\/h3>\n<ul>\n<li>einseitig bedruckt<\/li>\n<li>Gleiches Design f\u00fcr alle Schilder<\/li>\n<li>Unterschiedliches Design f\u00fcr jedes Schild<\/li>\n<\/ul>\n<p>W\u00e4hlen Sie die gew\u00fcnschten Optionen und laden Sie anschlie\u00dfend Ihre druckfertige Datei hoch oder nutzen Sie einen der verf\u00fcgbaren Designservices, um die Bestellung abzuschlie\u00dfen.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Aluminiumverbundplatte Gold geb\u00fcrstet als Freiform mit bis zu 4 Konturschnitten mit einseitigem Druck. Individuell bedruckbares Schild mit Auswahl von Gr\u00f6\u00dfe, Material und Designoption vor der Bestellung. Laden Sie Ihre druckfertige Datei hoch oder nutzen Sie den verf\u00fcgbaren Designservice.<\/p>\n","protected":false},"featured_media":61833,"comment_status":"open","ping_status":"closed","template":"","meta":{"nf_dc_page":""},"product_brand":[],"product_cat":[3845],"product_tag":[3847,3657,3500,3732,3846],"class_list":["post-61832","product","type-product","status-publish","has-post-thumbnail","product_cat-schilder-und-werbeschilder","product_tag-aluminiumverbund","product_tag-individueller-druck","product_tag-uv-dtf","product_tag-werbeschilder","product_tag-werbeschilder-2","first","instock","taxable","shipping-taxable","purchasable","product-type-variable","has-default-attributes","add-to-wishlist-before_image"],"_links":{"self":[{"href":"https:\/\/amanos.shop\/de\/wp-json\/wp\/v2\/product\/61832","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/amanos.shop\/de\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/amanos.shop\/de\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/amanos.shop\/de\/wp-json\/wp\/v2\/comments?post=61832"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/amanos.shop\/de\/wp-json\/wp\/v2\/media\/61833"}],"wp:attachment":[{"href":"https:\/\/amanos.shop\/de\/wp-json\/wp\/v2\/media?parent=61832"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/amanos.shop\/de\/wp-json\/wp\/v2\/product_brand?post=61832"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/amanos.shop\/de\/wp-json\/wp\/v2\/product_cat?post=61832"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/amanos.shop\/de\/wp-json\/wp\/v2\/product_tag?post=61832"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}