{"id":49351,"date":"2026-08-19T11:59:11","date_gmt":"2026-08-19T09:59:11","guid":{"rendered":"https:\/\/amanos.shop\/?post_type=product&#038;p=49351"},"modified":"2026-08-19T11:59:11","modified_gmt":"2026-08-19T09:59:11","slug":"nassleimetiketten-fur-flaschenhalse-168-cm-x-64-cm","status":"publish","type":"product","link":"https:\/\/amanos.shop\/de\/produkt\/nassleimetiketten-fur-flaschenhalse-168-cm-x-64-cm\/","title":{"rendered":"Nassleimetiketten \u2013 f\u00fcr Flaschenh\u00e4lse \u2013 16,8 cm \u00d7 6,4 cm"},"content":{"rendered":"<p>Nassleimetiketten \u2013 f\u00fcr Flaschenh\u00e4lse \u2013 16,8 cm \u00d7 6,4 cm eignen sich f\u00fcr Anwendungen mit Nassleim und lassen sich passend zu Ihrer Verpackung oder Ihrem Produkt individuell gestalten.<\/p>\n<h3>Passende Optionen ausw\u00e4hlen<\/h3>\n<ul>\n<li><strong>Material:<\/strong> W\u00e4hlen Sie eine der verf\u00fcgbaren Optionen auf dieser Seite.<\/li>\n<\/ul>\n<h3>Produktdetails<\/h3>\n<ul>\n<li><strong>Gr\u00f6\u00dfe:<\/strong> 16,8 cm \u00d7 6,4 cm<\/li>\n<li><strong>Druckverfahren:<\/strong> UV-DTF<\/li>\n<\/ul>\n<h3>Verf\u00fcgbare Mengen<\/h3>\n<p>500, 1.000, 2.500, 5.000 und 10.000 St\u00fcck. W\u00e4hlen Sie die gew\u00fcnschte Menge, um den entsprechenden Preis anzuzeigen.<\/p>\n<h3>Druckdaten &amp; Design<\/h3>\n<p>Laden Sie Ihre druckfertige Datei hoch oder nutzen Sie die Design-Tools auf der Produktseite. Pr\u00fcfen Sie Design und Produktauswahl, bevor Sie den Artikel in den Warenkorb legen.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Nassleimetiketten \u2013 f\u00fcr Flaschenh\u00e4lse \u2013 16,8 cm \u00d7 6,4 cm eignen sich f\u00fcr Anwendungen mit Nassleim und lassen sich passend zu Ihrer Verpackung oder Ihrem Produkt individuell gestalten. W\u00e4hlen Sie die passende Material und laden Sie anschlie\u00dfend Ihre druckfertige Datei hoch oder starten Sie Ihr Design auf der Produktseite.<\/p>\n","protected":false},"featured_media":0,"comment_status":"open","ping_status":"closed","template":"","meta":{"nf_dc_page":""},"product_brand":[],"product_cat":[3631],"product_tag":[3633,3632,3499,3500],"class_list":["post-49351","product","type-product","status-publish","product_cat-etiketten-auf-rolle","product_tag-nassleim","product_tag-personalisierung","product_tag-rollenetiketten","product_tag-uv-dtf","first","instock","taxable","shipping-taxable","purchasable","product-type-variable","has-default-attributes","add-to-wishlist-before_image"],"_links":{"self":[{"href":"https:\/\/amanos.shop\/de\/wp-json\/wp\/v2\/product\/49351","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/amanos.shop\/de\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/amanos.shop\/de\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/amanos.shop\/de\/wp-json\/wp\/v2\/comments?post=49351"}],"wp:attachment":[{"href":"https:\/\/amanos.shop\/de\/wp-json\/wp\/v2\/media?parent=49351"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/amanos.shop\/de\/wp-json\/wp\/v2\/product_brand?post=49351"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/amanos.shop\/de\/wp-json\/wp\/v2\/product_cat?post=49351"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/amanos.shop\/de\/wp-json\/wp\/v2\/product_tag?post=49351"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}