{"id":49344,"date":"2026-08-19T11:59:09","date_gmt":"2026-08-19T09:59:09","guid":{"rendered":"https:\/\/amanos.shop\/?post_type=product&#038;p=49344"},"modified":"2026-08-19T11:59:10","modified_gmt":"2026-08-19T09:59:10","slug":"nassleimetiketten-mit-heisfolienpragung-a5-hoch-148-x-210-cm","status":"publish","type":"product","link":"https:\/\/amanos.shop\/de\/produkt\/nassleimetiketten-mit-heisfolienpragung-a5-hoch-148-x-210-cm\/","title":{"rendered":"Nassleimetiketten mit Hei\u00dffolienpr\u00e4gung \u2013 A5 hoch \u2013 14,8 \u00d7 21,0 cm"},"content":{"rendered":"<p>Nassleimetiketten mit Hei\u00dffolienpr\u00e4gung \u2013 A5 hoch \u2013 14,8 \u00d7 21,0 cm verbinden Nassleimetiketten mit einer Hei\u00dffolienpr\u00e4gung f\u00fcr eine hochwertige Veredelung.<\/p>\n<h3>Passende Optionen ausw\u00e4hlen<\/h3>\n<ul>\n<li><strong>Material:<\/strong> W\u00e4hlen Sie eine der verf\u00fcgbaren Optionen auf dieser Seite.<\/li>\n<\/ul>\n<h3>Produktdetails<\/h3>\n<ul>\n<li><strong>Gr\u00f6\u00dfe:<\/strong> 14,8 \u00d7 21,0 cm<\/li>\n<li><strong>Druckverfahren:<\/strong> UV-DTF<\/li>\n<\/ul>\n<h3>Verf\u00fcgbare Mengen<\/h3>\n<p>500, 1.000, 2.500, 5.000 und 10.000 St\u00fcck. W\u00e4hlen Sie die gew\u00fcnschte Menge, um den entsprechenden Preis anzuzeigen.<\/p>\n<h3>Druckdaten &amp; Design<\/h3>\n<p>Laden Sie Ihre druckfertige Datei hoch oder nutzen Sie die Design-Tools auf der Produktseite. Pr\u00fcfen Sie Design und Produktauswahl, bevor Sie den Artikel in den Warenkorb legen.<\/p>\n<h3>Hinweis<\/h3>\n<ul>\n<li>Die Hei\u00dffolienpr\u00e4gung ist Bestandteil dieser Produktausf\u00fchrung.<\/li>\n<\/ul>\n","protected":false},"excerpt":{"rendered":"<p>Nassleimetiketten mit Hei\u00dffolienpr\u00e4gung \u2013 A5 hoch \u2013 14,8 \u00d7 21,0 cm verbinden Nassleimetiketten mit einer Hei\u00dffolienpr\u00e4gung f\u00fcr eine hochwertige Veredelung. W\u00e4hlen Sie die passende Material und laden Sie anschlie\u00dfend Ihre druckfertige Datei hoch oder starten Sie Ihr Design auf der Produktseite.<\/p>\n","protected":false},"featured_media":0,"comment_status":"open","ping_status":"closed","template":"","meta":{"nf_dc_page":""},"product_brand":[],"product_cat":[3631],"product_tag":[3634,3633,3632,3499,3500],"class_list":["post-49344","product","type-product","status-publish","product_cat-etiketten-auf-rolle","product_tag-heisfolienpragung","product_tag-nassleim","product_tag-personalisierung","product_tag-rollenetiketten","product_tag-uv-dtf","first","instock","taxable","shipping-taxable","purchasable","product-type-variable","has-default-attributes","add-to-wishlist-before_image"],"_links":{"self":[{"href":"https:\/\/amanos.shop\/de\/wp-json\/wp\/v2\/product\/49344","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/amanos.shop\/de\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/amanos.shop\/de\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/amanos.shop\/de\/wp-json\/wp\/v2\/comments?post=49344"}],"wp:attachment":[{"href":"https:\/\/amanos.shop\/de\/wp-json\/wp\/v2\/media?parent=49344"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/amanos.shop\/de\/wp-json\/wp\/v2\/product_brand?post=49344"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/amanos.shop\/de\/wp-json\/wp\/v2\/product_cat?post=49344"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/amanos.shop\/de\/wp-json\/wp\/v2\/product_tag?post=49344"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}