{"id":25899,"date":"2026-08-13T10:31:57","date_gmt":"2026-08-13T08:31:57","guid":{"rendered":"https:\/\/amanos.shop\/product\/datumsstempel-mit-zwei-individuellen-textfeldern-oberhalb-und-unterhalb-des-datums-41-x-9-mm-shiny-bp-826d\/"},"modified":"2026-08-13T12:45:04","modified_gmt":"2026-08-13T10:45:04","slug":"datumsstempel-mit-zwei-individuellen-textfeldern-oberhalb-und-unterhalb-des-datums-41-x-9-mm-shiny-bp-826d","status":"publish","type":"product","link":"https:\/\/amanos.shop\/de\/produkt\/datumsstempel-mit-zwei-individuellen-textfeldern-oberhalb-und-unterhalb-des-datums-41-x-9-mm-shiny-bp-826d\/","title":{"rendered":"Datumsstempel mit zwei individuellen Textfeldern oberhalb und unterhalb des Datums \u2013 41 \u00d7 9 mm \u2013 Shiny BP-826D"},"content":{"rendered":"<h2>Datumsstempel mit zwei individuellen Textfeldern oberhalb und unterhalb des Datums \u2013 41 \u00d7 9 mm \u2013 Shiny BP-826D<\/h2>\n<p>n<\/p>\n<p>Selbstf\u00e4rbender Datumsstempel, Modell <strong>Shiny BP-826D (eco-line)<\/strong>, mit einem individuellen Textfeld oberhalb und einem weiteren unterhalb des Datums. Jedes Feld misst <strong>41 \u00d7 9 mm<\/strong>.<\/p>\n<p>n<\/p>\n<h3>Anforderungen an Text und Druckdaten<\/h3>\n<p>n<\/p>\n<ul>\nn<\/p>\n<li><strong>Mindestschriftgr\u00f6\u00dfe:<\/strong> 7 pt bei feiner Schrift und 6 pt bei fetter Schrift<\/li>\n<p>n<\/p>\n<li><strong>Mindestlinienst\u00e4rke:<\/strong> 1 pt, keine Haarlinien<\/li>\n<p>n<\/p>\n<li><strong>Sicherheitsabstand:<\/strong> 0,5 mm zum Rand<\/li>\n<p>n<\/p>\n<li><strong>Farbe der Abdruckelemente:<\/strong> 100 % Schwarz<\/li>\n<p>n<\/ul>\n<p>n<\/p>\n<p>Sie k\u00f6nnen den Service <strong>\u201eF\u00fcr mich gestalten\u201c<\/strong> ausw\u00e4hlen und die gew\u00fcnschten Textangaben \u00fcbermitteln. Anschlie\u00dfend setzt sich das Amanos-Team mit Ihnen in Verbindung, um den Entwurf vor der Produktion zu pr\u00fcfen und freizugeben.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Datumsstempel Shiny BP-826D (eco-line) mit zwei individuellen Textfeldern oberhalb und unterhalb des Datums, jeweils 41 \u00d7 9 mm.<\/p>\n","protected":false},"featured_media":24176,"comment_status":"open","ping_status":"closed","template":"","meta":{"nf_dc_page":""},"product_brand":[],"product_cat":[3151],"product_tag":[3456,3332],"class_list":["post-25899","product","type-product","status-publish","has-post-thumbnail","product_cat-datumsstempel","product_tag-datumsstempel-2","product_tag-shiny-bp-826d","first","instock","taxable","shipping-taxable","purchasable","product-type-variable","has-default-attributes","add-to-wishlist-before_image"],"_links":{"self":[{"href":"https:\/\/amanos.shop\/de\/wp-json\/wp\/v2\/product\/25899","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/amanos.shop\/de\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/amanos.shop\/de\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/amanos.shop\/de\/wp-json\/wp\/v2\/comments?post=25899"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/amanos.shop\/de\/wp-json\/wp\/v2\/media\/24176"}],"wp:attachment":[{"href":"https:\/\/amanos.shop\/de\/wp-json\/wp\/v2\/media?parent=25899"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/amanos.shop\/de\/wp-json\/wp\/v2\/product_brand?post=25899"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/amanos.shop\/de\/wp-json\/wp\/v2\/product_cat?post=25899"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/amanos.shop\/de\/wp-json\/wp\/v2\/product_tag?post=25899"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}