{"id":135054,"date":"2026-08-29T12:55:44","date_gmt":"2026-08-29T10:55:44","guid":{"rendered":"https:\/\/amanos.shop\/product\/magnetschild-autoform-einseitiger-druck\/"},"modified":"2026-08-29T12:55:44","modified_gmt":"2026-08-29T10:55:44","slug":"magnetschild-autoform-einseitiger-druck","status":"publish","type":"product","link":"https:\/\/amanos.shop\/de\/produkt\/magnetschild-autoform-einseitiger-druck\/","title":{"rendered":"Magnetschild \u2013 Autoform \u2013 einseitiger Druck"},"content":{"rendered":"<h2>Magnetschild \u2013 Autoform \u2013 einseitiger Druck<\/h2>\n<p>Magnetschild aus magnetischem Material mit PVC-Beschichtung, zur Befestigung auf magnetisierbaren Metalloberfl\u00e4chen. Das Produkt kann mit <strong>UV-DTF<\/strong> individualisiert werden und wird einseitig bedruckt.<\/p>\n<h3>Gr\u00f6\u00dfe<\/h3>\n<p>Verf\u00fcgbare Gr\u00f6\u00dfen bei Amanos: 10 \u00d7 10 cm, 20 \u00d7 20 cm, 35 \u00d7 35 cm.<\/p>\n<h3>Materialien und Veredelungen<\/h3>\n<p>W\u00e4hlen Sie aus den verf\u00fcgbaren Optionen das passende Material, die St\u00e4rke und die Veredelung f\u00fcr dieses Produkt.<\/p>\n<h3>Designmodus<\/h3>\n<p>Sie k\u00f6nnen dasselbe Design f\u00fcr alle Exemplare oder ein individuelles Design pro Exemplar w\u00e4hlen.<\/p>\n<h3>Designdatei<\/h3>\n<p>Laden Sie Ihre druckfertige Designdatei hoch oder nutzen Sie den bei Amanos verf\u00fcgbaren Designservice, um Ihre Bestellung abzuschlie\u00dfen.<\/p>\n<p><strong>Preis:<\/strong> Der angezeigte St\u00fcckpreis enth\u00e4lt 19 % MwSt. und variiert je nach Gr\u00f6\u00dfe, Material und Designmodus.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Magnetschild \u2013 Autoform \u2013 einseitiger Druck. Individualisierbar mit UV-DTF-Druck. Verf\u00fcgbare Gr\u00f6\u00dfen bei Amanos: 10 \u00d7 10 cm, 20 \u00d7 20 cm, 35 \u00d7 35 cm. W\u00e4hlen Sie Gr\u00f6\u00dfe, Material und Designmodus und laden Sie anschlie\u00dfend Ihre Designdatei hoch. Der angezeigte St\u00fcckpreis enth\u00e4lt 19 % MwSt. und variiert je nach gew\u00e4hlten Optionen.<\/p>\n","protected":false},"featured_media":135055,"comment_status":"open","ping_status":"closed","template":"","meta":{"nf_dc_page":""},"product_brand":[],"product_cat":[3845],"product_tag":[3657,3922,3921,3920,3500,3732],"class_list":["post-135054","product","type-product","status-publish","has-post-thumbnail","product_cat-schilder-und-werbeschilder","product_tag-individueller-druck","product_tag-magnet","product_tag-magnetplatte","product_tag-magnetschilder","product_tag-uv-dtf","product_tag-werbeschilder","first","instock","taxable","shipping-taxable","purchasable","product-type-variable","has-default-attributes","add-to-wishlist-before_image"],"_links":{"self":[{"href":"https:\/\/amanos.shop\/de\/wp-json\/wp\/v2\/product\/135054","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/amanos.shop\/de\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/amanos.shop\/de\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/amanos.shop\/de\/wp-json\/wp\/v2\/comments?post=135054"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/amanos.shop\/de\/wp-json\/wp\/v2\/media\/135055"}],"wp:attachment":[{"href":"https:\/\/amanos.shop\/de\/wp-json\/wp\/v2\/media?parent=135054"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/amanos.shop\/de\/wp-json\/wp\/v2\/product_brand?post=135054"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/amanos.shop\/de\/wp-json\/wp\/v2\/product_cat?post=135054"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/amanos.shop\/de\/wp-json\/wp\/v2\/product_tag?post=135054"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}