{"id":123274,"date":"2026-08-28T17:39:33","date_gmt":"2026-08-28T15:39:33","guid":{"rendered":"https:\/\/amanos.shop\/?post_type=product&#038;p=123274"},"modified":"2026-08-28T17:39:33","modified_gmt":"2026-08-28T15:39:33","slug":"stadur-leichtschaumplatte-sprechblasenform-einseitiger-druck","status":"publish","type":"product","link":"https:\/\/amanos.shop\/de\/produkt\/stadur-leichtschaumplatte-sprechblasenform-einseitiger-druck\/","title":{"rendered":"STADUR-Leichtschaumplatte \u2013 Sprechblasenform \u2013 einseitiger Druck"},"content":{"rendered":"<h2>STADUR-Leichtschaumplatte \u2013 Sprechblasenform \u2013 einseitiger Druck<\/h2>\n<p>STADUR VISCOM SIGN EASYPRINT Leichtschaumplatte f\u00fcr individuell gestaltete Schilder und Beschilderungen, mit verschiedenen St\u00e4rken und Oberfl\u00e4chenoptionen. Das Produkt kann mit <strong>UV-DTF<\/strong> personalisiert werden; der Druck erfolgt einseitig.<\/p>\n<h3>Gr\u00f6\u00dfe<\/h3>\n<p>Bei Amanos verf\u00fcgbare Gr\u00f6\u00dfen: 10 \u00d7 10 cm, 20 \u00d7 20 cm, 35 \u00d7 35 cm.<\/p>\n<h3>Materialien und Ausf\u00fchrungen<\/h3>\n<p>W\u00e4hlen Sie das passende Material, die St\u00e4rke und die Ausf\u00fchrung aus den f\u00fcr dieses Produkt verf\u00fcgbaren Optionen.<\/p>\n<h3>Designmodus<\/h3>\n<p>Sie k\u00f6nnen dasselbe Design f\u00fcr alle Exemplare oder ein individuelles Design pro Exemplar w\u00e4hlen.<\/p>\n<h3>Designdatei<\/h3>\n<p>Laden Sie Ihre druckfertige Designdatei hoch oder nutzen Sie den bei Amanos verf\u00fcgbaren Designservice, um die Bestellung abzuschlie\u00dfen.<\/p>\n<p><strong>Preis:<\/strong> Der angezeigte Preis gilt pro St\u00fcck, inklusive 19 % MwSt., und variiert je nach Gr\u00f6\u00dfe, Material und Designmodus.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>STADUR-Leichtschaumplatte \u2013 Sprechblasenform \u2013 einseitiger Druck. Mit UV-DTF-Druck personalisierbar. Bei Amanos verf\u00fcgbare Gr\u00f6\u00dfen: 10 \u00d7 10 cm, 20 \u00d7 20 cm, 35 \u00d7 35 cm. W\u00e4hlen Sie Gr\u00f6\u00dfe, Material und Designmodus und laden Sie anschlie\u00dfend Ihre Designdatei hoch. Der angezeigte Preis gilt pro St\u00fcck, inklusive 19 % MwSt., und variiert je nach gew\u00e4hlten Optionen.<\/p>\n","protected":false},"featured_media":123275,"comment_status":"open","ping_status":"closed","template":"","meta":{"nf_dc_page":""},"product_brand":[],"product_cat":[3845],"product_tag":[3657,3867,3899,3500,3732,3846],"class_list":["post-123274","product","type-product","status-publish","has-post-thumbnail","product_cat-schilder-und-werbeschilder","product_tag-individueller-druck","product_tag-leichtschaum","product_tag-stadur","product_tag-uv-dtf","product_tag-werbeschilder","product_tag-werbeschilder-2","first","instock","taxable","shipping-taxable","purchasable","product-type-variable","has-default-attributes","add-to-wishlist-before_image"],"_links":{"self":[{"href":"https:\/\/amanos.shop\/de\/wp-json\/wp\/v2\/product\/123274","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/amanos.shop\/de\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/amanos.shop\/de\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/amanos.shop\/de\/wp-json\/wp\/v2\/comments?post=123274"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/amanos.shop\/de\/wp-json\/wp\/v2\/media\/123275"}],"wp:attachment":[{"href":"https:\/\/amanos.shop\/de\/wp-json\/wp\/v2\/media?parent=123274"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/amanos.shop\/de\/wp-json\/wp\/v2\/product_brand?post=123274"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/amanos.shop\/de\/wp-json\/wp\/v2\/product_cat?post=123274"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/amanos.shop\/de\/wp-json\/wp\/v2\/product_tag?post=123274"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}